{"id":4331,"date":"2018-04-13T10:28:30","date_gmt":"2018-04-13T10:28:30","guid":{"rendered":"https:\/\/demo2.madrasthemes.com\/electro\/?post_type=static_block&amp;p=4331"},"modified":"2018-04-13T10:28:30","modified_gmt":"2018-04-13T10:28:30","slug":"tv-audio-fullwidth-megamenu-item","status":"publish","type":"mas_static_content","link":"https:\/\/tecnolock.cl\/Tienda\/?mas_static_content=tv-audio-fullwidth-megamenu-item","title":{"rendered":"TV &#038; Audio Fullwidth Megamenu Item"},"content":{"rendered":"<p>[vc_row el_class=&#8221;image-vertical-align&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<ul>\n<li class=\"nav-title\">Televisions<\/li>\n<li><a href=\"#\">Smart TVs<\/a><\/li>\n<li><a href=\"#\">4K TVs<\/a><\/li>\n<li><a href=\"#\">Full HD TVs<\/a><\/li>\n<li><a href=\"#\">Large Screen TVs<\/a><\/li>\n<li><a href=\"#\">32 inch TVs<\/a><\/li>\n<li><a href=\"#\">39-43 inch TV<\/a><\/li>\n<li><a href=\"#\">48 &amp; Above<\/a><\/li>\n<\/ul>\n<ul>\n<li class=\"nav-title\">Home Audio\/Video<\/li>\n<li><a href=\"#\">Speakers<\/a><\/li>\n<li><a href=\"#\">Home Theaters<\/a><\/li>\n<li><a href=\"#\">Projectors<\/a><\/li>\n<li><a href=\"#\">Headphones<\/a><\/li>\n<li><a href=\"#\">Noise Cancelling Headphones<\/a><\/li>\n<li><a href=\"#\">Soundbars<\/a><\/li>\n<li><a href=\"#\">Headphones with Mic<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<ul>\n<li class=\"nav-title\">Shop by Brand<\/li>\n<li><a href=\"#\">VU<\/a><\/li>\n<li><a href=\"#\">Mi LED Smart TVs<\/a><\/li>\n<li><a href=\"#\">Samsung<\/a><\/li>\n<li><a href=\"#\">Panasonic<\/a><\/li>\n<li><a href=\"#\">TCL<\/a><\/li>\n<li><a href=\"#\">Sanyo<\/a><\/li>\n<li><a href=\"#\">Micromax<\/a><\/li>\n<\/ul>\n<ul>\n<li class=\"nav-title\">Shop by Brand<\/li>\n<li><a href=\"#\">JBL<\/a><\/li>\n<li><a href=\"#\">Sony<\/a><\/li>\n<li><a href=\"#\">Ultimate ears<\/a><\/li>\n<li><a href=\"#\">Philips<\/a><\/li>\n<li><a href=\"#\">Protronics<\/a><\/li>\n<li><a href=\"#\">Saregama<\/a><\/li>\n<li><a href=\"#\">Harmon Kardon<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<ul>\n<li class=\"nav-title\">Other Home Entertainment<\/li>\n<li><a href=\"#\">Home Theater Systems<\/a><\/li>\n<li><a href=\"#\">Projectors &amp; Accessoires<\/a><\/li>\n<li><a href=\"#\">Set top Boxes<\/a><\/li>\n<li><a href=\"#\">Streaming Media Players<\/a><\/li>\n<li><a href=\"#\">DVD &amp; Blu-ray Players<\/a><\/li>\n<li><a href=\"#\">Cables<\/a><\/li>\n<li><a href=\"#\">Audio-video Accessories<\/a><\/li>\n<\/ul>\n<ul>\n<li class=\"nav-title\">Shop By Price<\/li>\n<li><a href=\"#\">Below Rs. 100$<\/a><\/li>\n<li><a href=\"#\">101$ &#8211; 199$<\/a><\/li>\n<li><a href=\"#\">200$ &#8211; 299$<\/a><\/li>\n<li><a href=\"#\">300$ &#8211; 399$<\/a><\/li>\n<li><a href=\"#\">400$ &#8211; 499$<\/a><\/li>\n<li><a href=\"#\">500$ &#8211; 599$<\/a><\/li>\n<li><a href=\"#\">600$ and Above<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;5021&#8243; img_size=&#8221;large&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_single_image image=&#8221;5021&#8243; img_size=&#8221;large&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"template":"","class_list":["post-4331","mas_static_content","type-mas_static_content","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tecnolock.cl\/Tienda\/wp-json\/wp\/v2\/mas_static_content\/4331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnolock.cl\/Tienda\/wp-json\/wp\/v2\/mas_static_content"}],"about":[{"href":"https:\/\/tecnolock.cl\/Tienda\/wp-json\/wp\/v2\/types\/mas_static_content"}],"version-history":[{"count":0,"href":"https:\/\/tecnolock.cl\/Tienda\/wp-json\/wp\/v2\/mas_static_content\/4331\/revisions"}],"wp:attachment":[{"href":"https:\/\/tecnolock.cl\/Tienda\/wp-json\/wp\/v2\/media?parent=4331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}